{"id":978,"date":"2024-05-27T03:07:26","date_gmt":"2024-05-27T03:07:26","guid":{"rendered":"https:\/\/www.progan.co\/?page_id=978"},"modified":"2026-03-14T07:11:57","modified_gmt":"2026-03-14T12:11:57","slug":"logistica","status":"publish","type":"page","link":"https:\/\/www.progan.co\/es\/home2\/logistica\/","title":{"rendered":"Log\u00edstica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"978\" class=\"elementor elementor-978\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3bc9cb e-con-full animated-slow e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no elementor-invisible e-con e-parent\" data-id=\"b3bc9cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f228c48 elementor-widget elementor-widget-heading\" data-id=\"f228c48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Log\u00edstica global y soluciones<br> personalizadas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f54e76 elementor-widget elementor-widget-spacer\" data-id=\"4f54e76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a8d5ec e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"5a8d5ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5a34ca7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"5a34ca7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-412a89a elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"412a89a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Operaciones de transporte,<\/span> embalaje, control de calidad y trazabilidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5243650 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5243650\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfSu cadena de suministro le est\u00e1 dando un dolor de cabeza? Creamos Progan Logistics para cumplir con las operaciones y control de calidad de nuestros socios y productores locales.\u00a0<br \/><br \/>Con presencia en los <strong>EE. UU., Colombia, Brasil y Europa,<\/strong> creamos una cadena de suministro s\u00f3lida con equipos locales, lo cual nos permite operar de forma mucho m\u00e1s f\u00e1cil y confiable para nuestros clientes. En nuestros almacenes ofrecemos log\u00edstica de terceros y soluciones de control de calidad con soporte de laboratorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21344d4 elementor-widget-divider--view-line_icon elementor-widget-divider--element-align-left elementor-view-default elementor-widget elementor-widget-divider\" data-id=\"21344d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d8ca17 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"4d8ca17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31a194c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"31a194c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"591\" height=\"231\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096300.png\" class=\"attachment-full size-full wp-image-987\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096300.png 591w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096300-300x117.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096300-18x7.png 18w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9734e3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b9734e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"591\" height=\"231\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096301.png\" class=\"attachment-full size-full wp-image-986\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096301.png 591w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096301-300x117.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096301-18x7.png 18w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74a1680 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"74a1680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"591\" height=\"231\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096302.png\" class=\"attachment-full size-full wp-image-985\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096302.png 591w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096302-300x117.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096302-18x7.png 18w\" sizes=\"(max-width: 591px) 100vw, 591px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf0b0f8 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"bf0b0f8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87ced7b elementor-widget elementor-widget-heading\" data-id=\"87ced7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestras soluciones log\u00edsticas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97bd2a3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"97bd2a3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-295433a e-grid elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"295433a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34b0a61 elementor-widget elementor-widget-image\" data-id=\"34b0a61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"494\" height=\"690\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096360.png\" class=\"attachment-full size-full wp-image-996\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096360.png 494w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096360-215x300.png 215w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096360-9x12.png 9w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-510b430 elementor-widget elementor-widget-image\" data-id=\"510b430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"494\" height=\"690\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096362.png\" class=\"attachment-full size-full wp-image-994\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096362.png 494w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096362-215x300.png 215w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096362-9x12.png 9w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f0f201 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2f0f201\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"608\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096361.png\" class=\"attachment-full size-full wp-image-995\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096361.png 412w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096361-203x300.png 203w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096361-8x12.png 8w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23ac0c1 e-grid e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"23ac0c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b7be44 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"6b7be44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Almacenamiento                <\/h3>\n                        \t\t  \t<p>Contamos con bodegas de almacenamiento en seco de \u00faltima generaci\u00f3n para harinas de prote\u00edna animal, aceites, grasas y minerales a granel; ubicadas estrat\u00e9gicamente a lo largo de Am\u00e9rica Latina, Estados Unidos y Europa, que ofrecen altos est\u00e1ndares de calidad y se ajustan a las necesidades de cada uno de nuestros clientes.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2103d69 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"2103d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Log\u00edstica                <\/h3>\n                        \t\t  \t<p>Somos la soluci\u00f3n para su punto de venta, contamos con toda la log\u00edstica necesaria para contribuir y surtir su cadena de suministro; ofrecemos desde EXW hasta DDP y servicios de transbordo.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80c8534 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"80c8534\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Comercio Exterior (corretaje)                <\/h3>\n                        \t\t  \t<p>Ofrecemos servicios de importaci\u00f3n y exportaci\u00f3n de acuerdo a sus requerimientos. Nuestras operaciones son recepcionadas desde nuestras oficinas ubicadas en Estados Unidos, Colombia, Brasil y Pa\u00edses Bajos; manejando una operaci\u00f3n internacional ajustada a las pol\u00edticas de cada regi\u00f3n.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a68c68 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"8a68c68\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7886fa0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"7886fa0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5a232 elementor-widget elementor-widget-image\" data-id=\"5a5a232\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"262\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096363.png\" class=\"attachment-full size-full wp-image-1006\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096363.png 390w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096363-300x202.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096363-18x12.png 18w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-deb55f7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"deb55f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-272231c elementor-widget elementor-widget-image\" data-id=\"272231c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"302\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096364.png\" class=\"attachment-full size-full wp-image-1005\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096364.png 390w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096364-300x232.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096364-15x12.png 15w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20414c8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"20414c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f018c1 elementor-widget elementor-widget-image\" data-id=\"5f018c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"282\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096365.png\" class=\"attachment-full size-full wp-image-1004\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096365.png 390w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096365-300x217.png 300w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Group-48096365-18x12.png 18w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ff264e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"4ff264e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d367a46 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d367a46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e12d21 elementor-widget elementor-widget-author-box\" data-id=\"3e12d21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f59802 elementor-widget elementor-widget-text-editor\" data-id=\"9f59802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualmente obtenemos prote\u00ednas, grasas y aceites animales de diferentes especies de Am\u00e9rica Latina y Europa. Luego de a\u00f1os como fabricantes, identificamos y creamos una s\u00f3lida red de 22 proveedores de diversos productos, garantizando siempre primero la calidad y trazabilidad,<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f976fe0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"f976fe0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b58a81 elementor-widget elementor-widget-author-box\" data-id=\"1b58a81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e48995 elementor-widget elementor-widget-text-editor\" data-id=\"4e48995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros centros log\u00edsticos ubicados estrat\u00e9gicamente, nos permiten mover grandes cantidades de vol\u00famenes de manera eficiente, entregando cada ingrediente a su puerta sin contratiempos y de acuerdo a sus necesidades (es decir, transbordo de granel a super sacos y viceversa). Tambi\u00e9n podemos ofrecer su punto de venta m\u00e1s conveniente, desde EXW hasta DDP.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e0c930 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"7e0c930\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1472ffb elementor-widget elementor-widget-author-box\" data-id=\"1472ffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e14c5b1 elementor-widget elementor-widget-text-editor\" data-id=\"e14c5b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con alrededor de 45 a\u00f1os de experiencia combinada, despu\u00e9s de operar 20 plantas de procesamiento y una planta de fabricaci\u00f3n de alimentos para mascotas, nuestro equipo de adquisiciones est\u00e1 formado por especialistas en abastecimiento global, trazabilidad, control de calidad y los mejores ingredientes para mascotas de calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42f874f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"42f874f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-50938cf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"50938cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd323af elementor-widget elementor-widget-heading\" data-id=\"fd323af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Puertos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f053fb elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5f053fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con operaciones en <strong><span style=\"color: #3d9136;\">Estados Unidos, Colombia, Brasil y asociaciones en Europa y Pa\u00edses Bajos,<\/span><\/strong> nuestro equipo de log\u00edstica est\u00e1 listo para manejar todas sus necesidades de transporte alrededor\u00a0 del mundo, si las reglamentaciones y pol\u00edticas del pa\u00eds lo permiten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f74b281 elementor-widget-divider--view-line_icon elementor-widget-divider--element-align-right elementor-view-default elementor-widget elementor-widget-divider\" data-id=\"f74b281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-931b96a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"931b96a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d650bd5 e-grid e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d650bd5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-795ba77 elementor-widget elementor-widget-image\" data-id=\"795ba77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"319\" height=\"443\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1689.png\" class=\"attachment-full size-full wp-image-1012\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1689.png 319w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1689-216x300.png 216w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1689-9x12.png 9w\" sizes=\"(max-width: 319px) 100vw, 319px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fab094f elementor-widget elementor-widget-image\" data-id=\"fab094f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"318\" height=\"443\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1690.png\" class=\"attachment-full size-full wp-image-1011\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1690.png 318w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1690-215x300.png 215w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1690-9x12.png 9w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f23518 elementor-widget elementor-widget-image\" data-id=\"5f23518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"319\" height=\"443\" src=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1691.png\" class=\"attachment-full size-full wp-image-1010\" alt=\"\" srcset=\"https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1691.png 319w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1691-216x300.png 216w, https:\/\/www.progan.co\/wp-content\/uploads\/2024\/05\/Rectangle-1691-9x12.png 9w\" sizes=\"(max-width: 319px) 100vw, 319px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Log\u00edstica global y soluciones personalizadas Operaciones de transporte, embalaje, control de calidad y trazabilidad. \u00bfSu cadena de suministro le est\u00e1 dando un dolor de cabeza? Creamos Progan Logistics para cumplir con las operaciones y control de calidad de nuestros socios y productores locales.\u00a0 Con presencia en los EE. UU., Colombia, Brasil y Europa, creamos una cadena de suministro s\u00f3lida con equipos locales, lo cual nos permite operar de forma mucho m\u00e1s f\u00e1cil y confiable para nuestros clientes. En nuestros almacenes ofrecemos log\u00edstica de terceros y soluciones de control de calidad con soporte de laboratorio. Nuestras soluciones log\u00edsticas Almacenamiento Contamos con bodegas de almacenamiento en seco de \u00faltima generaci\u00f3n para harinas de prote\u00edna animal, aceites, grasas y minerales a granel; ubicadas estrat\u00e9gicamente a lo largo de Am\u00e9rica Latina, Estados Unidos y Europa, que ofrecen altos est\u00e1ndares de calidad y se ajustan a las necesidades de cada uno de nuestros clientes. Log\u00edstica Somos la soluci\u00f3n para su punto de venta, contamos con toda la log\u00edstica necesaria para contribuir y surtir su cadena de suministro; ofrecemos desde EXW hasta DDP y servicios de transbordo. Comercio Exterior (corretaje) Ofrecemos servicios de importaci\u00f3n y exportaci\u00f3n de acuerdo a sus requerimientos. Nuestras operaciones son recepcionadas desde nuestras oficinas ubicadas en Estados Unidos, Colombia, Brasil y Pa\u00edses Bajos; manejando una operaci\u00f3n internacional ajustada a las pol\u00edticas de cada regi\u00f3n. Actualmente obtenemos prote\u00ednas, grasas y aceites animales de diferentes especies de Am\u00e9rica Latina y Europa. Luego de a\u00f1os como fabricantes, identificamos y creamos una s\u00f3lida red de 22 proveedores de diversos productos, garantizando siempre primero la calidad y trazabilidad, Nuestros centros log\u00edsticos ubicados estrat\u00e9gicamente, nos permiten mover grandes cantidades de vol\u00famenes de manera eficiente, entregando cada ingrediente a su puerta sin contratiempos y de acuerdo a sus necesidades (es decir, transbordo de granel a super sacos y viceversa). Tambi\u00e9n podemos ofrecer su punto de venta m\u00e1s conveniente, desde EXW hasta DDP. Con alrededor de 45 a\u00f1os de experiencia combinada, despu\u00e9s de operar 20 plantas de procesamiento y una planta de fabricaci\u00f3n de alimentos para mascotas, nuestro equipo de adquisiciones est\u00e1 formado por especialistas en abastecimiento global, trazabilidad, control de calidad y los mejores ingredientes para mascotas de calidad. Puertos Con operaciones en Estados Unidos, Colombia, Brasil y asociaciones en Europa y Pa\u00edses Bajos, nuestro equipo de log\u00edstica est\u00e1 listo para manejar todas sus necesidades de transporte alrededor\u00a0 del mundo, si las reglamentaciones y pol\u00edticas del pa\u00eds lo permiten.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":26,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-978","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/pages\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":15,"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/pages\/978\/revisions"}],"predecessor-version":[{"id":5022,"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/pages\/978\/revisions\/5022"}],"up":[{"embeddable":true,"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/pages\/26"}],"wp:attachment":[{"href":"https:\/\/www.progan.co\/es\/wp-json\/wp\/v2\/media?parent=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}